{"id":3615,"date":"2023-11-02T19:37:10","date_gmt":"2023-11-02T18:37:10","guid":{"rendered":"https:\/\/www.danieleinzinna.com\/?page_id=3615"},"modified":"2023-11-02T19:46:20","modified_gmt":"2023-11-02T18:46:20","slug":"salvatore-ilenia","status":"publish","type":"page","link":"https:\/\/www.danieleinzinna.com\/index.php\/salvatore-ilenia\/","title":{"rendered":"Salvatore + Ilenia"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/1_D4N4719-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3617\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/1_D4N4719-Modifica.jpg\" alt=\"\" class=\"wp-image-3617\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/1_D4N4719-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/1_D4N4719-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/1_D4N4719-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/2_D4N0168-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3616\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/2_D4N0168-Modifica.jpg\" alt=\"\" class=\"wp-image-3616\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/2_D4N0168-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/2_D4N0168-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/2_D4N0168-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/3_D4N0022-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3618\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/3_D4N0022-Modifica.jpg\" alt=\"\" class=\"wp-image-3618\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/3_D4N0022-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/3_D4N0022-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/3_D4N0022-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/4_D4N0647-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3620\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/4_D4N0647-Modifica.jpg\" alt=\"\" class=\"wp-image-3620\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/4_D4N0647-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/4_D4N0647-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/4_D4N0647-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/5_D4N0040-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3619\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/5_D4N0040-Modifica.jpg\" alt=\"\" class=\"wp-image-3619\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/5_D4N0040-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/5_D4N0040-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/6_D4N0655-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3621\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/6_D4N0655-Modifica.jpg\" alt=\"\" class=\"wp-image-3621\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/6_D4N0655-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/6_D4N0655-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/6_D4N0655-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/7_D4N0163-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3622\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/7_D4N0163-Modifica.jpg\" alt=\"\" class=\"wp-image-3622\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/7_D4N0163-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/7_D4N0163-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/8_D4N0569-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3623\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/8_D4N0569-Modifica.jpg\" alt=\"\" class=\"wp-image-3623\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/8_D4N0569-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/8_D4N0569-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/9XT3D0190-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"1280\" data-id=\"3624\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/9XT3D0190-Modifica.jpg\" alt=\"\" class=\"wp-image-3624\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/9XT3D0190-Modifica.jpg 853w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/9XT3D0190-Modifica-768x1152.jpg 768w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/10_D4N0566-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3627\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/10_D4N0566-Modifica.jpg\" alt=\"\" class=\"wp-image-3627\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/10_D4N0566-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/10_D4N0566-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/10_D4N0566-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/11_D4N4745-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3625\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/11_D4N4745-Modifica.jpg\" alt=\"\" class=\"wp-image-3625\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/11_D4N4745-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/11_D4N4745-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/11_D4N4745-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/12_D4N0073-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3626\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/12_D4N0073-Modifica.jpg\" alt=\"\" class=\"wp-image-3626\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/12_D4N0073-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/12_D4N0073-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/13_D4N0598-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3628\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/13_D4N0598-Modifica.jpg\" alt=\"\" class=\"wp-image-3628\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/13_D4N0598-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/13_D4N0598-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/13_D4N0598-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/14_D4N0181-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3629\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/14_D4N0181-Modifica.jpg\" alt=\"\" class=\"wp-image-3629\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/14_D4N0181-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/14_D4N0181-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/15XT3D0468-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" data-id=\"3630\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/15XT3D0468-Modifica.jpg\" alt=\"\" class=\"wp-image-3630\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/15XT3D0468-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/15XT3D0468-Modifica-900x600.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/15XT3D0468-Modifica-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/16XT3D0442-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" data-id=\"3631\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/16XT3D0442-Modifica.jpg\" alt=\"\" class=\"wp-image-3631\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/16XT3D0442-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/16XT3D0442-Modifica-900x600.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/16XT3D0442-Modifica-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/17_D4N4750-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3632\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/17_D4N4750-Modifica.jpg\" alt=\"\" class=\"wp-image-3632\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/17_D4N4750-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/17_D4N4750-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/17_D4N4750-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/18_D4N0620-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3633\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/18_D4N0620-Modifica.jpg\" alt=\"\" class=\"wp-image-3633\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/18_D4N0620-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/18_D4N0620-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/18_D4N0620-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/19_D4N0630-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3634\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/19_D4N0630-Modifica.jpg\" alt=\"\" class=\"wp-image-3634\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/19_D4N0630-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/19_D4N0630-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/19_D4N0630-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/20_D4N0067-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3635\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/20_D4N0067-Modifica.jpg\" alt=\"\" class=\"wp-image-3635\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/20_D4N0067-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/20_D4N0067-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/20_D4N0067-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/21_D4N0116-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3636\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/21_D4N0116-Modifica.jpg\" alt=\"\" class=\"wp-image-3636\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/21_D4N0116-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/21_D4N0116-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/21_D4N0116-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/22_D4N0666-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3637\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/22_D4N0666-Modifica.jpg\" alt=\"\" class=\"wp-image-3637\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/22_D4N0666-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/22_D4N0666-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/22_D4N0666-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/23_D4N0185-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3638\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/23_D4N0185-Modifica.jpg\" alt=\"\" class=\"wp-image-3638\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/23_D4N0185-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/23_D4N0185-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/24_D4N0253-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3639\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/24_D4N0253-Modifica.jpg\" alt=\"\" class=\"wp-image-3639\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/24_D4N0253-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/24_D4N0253-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/24_D4N0253-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/25_D4N0592-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3640\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/25_D4N0592-Modifica.jpg\" alt=\"\" class=\"wp-image-3640\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/25_D4N0592-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/25_D4N0592-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/26_D4N0708-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3641\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/26_D4N0708-Modifica.jpg\" alt=\"\" class=\"wp-image-3641\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/26_D4N0708-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/26_D4N0708-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/26_D4N0708-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/27_D4N0157-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3642\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/27_D4N0157-Modifica.jpg\" alt=\"\" class=\"wp-image-3642\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/27_D4N0157-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/27_D4N0157-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/27_D4N0157-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/28_D4N0122-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3643\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/28_D4N0122-Modifica.jpg\" alt=\"\" class=\"wp-image-3643\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/28_D4N0122-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/28_D4N0122-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/28_D4N0122-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/29_D4N4793-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3644\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/29_D4N4793-Modifica.jpg\" alt=\"\" class=\"wp-image-3644\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/29_D4N4793-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/29_D4N4793-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/29_D4N4793-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/30_D4N0227-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3645\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/30_D4N0227-Modifica.jpg\" alt=\"\" class=\"wp-image-3645\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/30_D4N0227-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/30_D4N0227-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/30_D4N0227-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/31_D4N0272-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3646\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/31_D4N0272-Modifica.jpg\" alt=\"\" class=\"wp-image-3646\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/31_D4N0272-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/31_D4N0272-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/31_D4N0272-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/32XT3D0416-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" data-id=\"3647\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/32XT3D0416-Modifica.jpg\" alt=\"\" class=\"wp-image-3647\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/32XT3D0416-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/32XT3D0416-Modifica-900x600.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/32XT3D0416-Modifica-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/33_D4N0389-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3648\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/33_D4N0389-Modifica.jpg\" alt=\"\" class=\"wp-image-3648\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/33_D4N0389-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/33_D4N0389-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/33_D4N0389-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/34_D4N0454-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3649\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/34_D4N0454-Modifica.jpg\" alt=\"\" class=\"wp-image-3649\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/34_D4N0454-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/34_D4N0454-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/34_D4N0454-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/35_D4N0540-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3650\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/35_D4N0540-Modifica.jpg\" alt=\"\" class=\"wp-image-3650\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/35_D4N0540-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/35_D4N0540-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/35_D4N0540-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/36_D4N0551-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3651\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/36_D4N0551-Modifica.jpg\" alt=\"\" class=\"wp-image-3651\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/36_D4N0551-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/36_D4N0551-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/37_D4N0611-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3652\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/37_D4N0611-Modifica.jpg\" alt=\"\" class=\"wp-image-3652\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/37_D4N0611-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/37_D4N0611-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/37_D4N0611-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/38_D4N0657-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3653\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/38_D4N0657-Modifica.jpg\" alt=\"\" class=\"wp-image-3653\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/38_D4N0657-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/38_D4N0657-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/39XT3D0432-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" data-id=\"3654\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/39XT3D0432-Modifica.jpg\" alt=\"\" class=\"wp-image-3654\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/39XT3D0432-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/39XT3D0432-Modifica-900x600.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/39XT3D0432-Modifica-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/40_D4N0667-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3655\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/40_D4N0667-Modifica.jpg\" alt=\"\" class=\"wp-image-3655\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/40_D4N0667-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/40_D4N0667-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/41_D4N0602-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3656\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/41_D4N0602-Modifica.jpg\" alt=\"\" class=\"wp-image-3656\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/41_D4N0602-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/41_D4N0602-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/41_D4N0602-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/42_D4N0746-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3657\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/42_D4N0746-Modifica.jpg\" alt=\"\" class=\"wp-image-3657\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/42_D4N0746-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/42_D4N0746-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/42_D4N0746-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/43_D4N0696-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"1280\" data-id=\"3659\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/43_D4N0696-Modifica.jpg\" alt=\"\" class=\"wp-image-3659\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/43_D4N0696-Modifica.jpg 852w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/43_D4N0696-Modifica-768x1154.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/44XT3D0626-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" data-id=\"3658\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/44XT3D0626-Modifica.jpg\" alt=\"\" class=\"wp-image-3658\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/44XT3D0626-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/44XT3D0626-Modifica-900x600.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/44XT3D0626-Modifica-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/45_D4N0672-Modifica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" data-id=\"3660\" src=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/45_D4N0672-Modifica.jpg\" alt=\"\" class=\"wp-image-3660\" srcset=\"https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/45_D4N0672-Modifica.jpg 1280w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/45_D4N0672-Modifica-900x599.jpg 900w, https:\/\/www.danieleinzinna.com\/wp-content\/uploads\/2023\/11\/45_D4N0672-Modifica-768x511.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3620,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/pages\/3615"}],"collection":[{"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/comments?post=3615"}],"version-history":[{"count":5,"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/pages\/3615\/revisions"}],"predecessor-version":[{"id":3667,"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/pages\/3615\/revisions\/3667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/media\/3620"}],"wp:attachment":[{"href":"https:\/\/www.danieleinzinna.com\/index.php\/wp-json\/wp\/v2\/media?parent=3615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}